{"id":4242,"date":"2016-09-06T15:14:33","date_gmt":"2016-09-06T15:14:33","guid":{"rendered":"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/"},"modified":"2017-09-22T19:58:45","modified_gmt":"2017-09-22T19:58:45","slug":"sitemap","status":"publish","type":"page","link":"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/","title":{"rendered":"Mapa de sitio"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":1738,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"sitemap.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4242","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hotel Las Brisas Ixtapa - Mapa De Sitio | Contenido<\/title>\n<meta name=\"description\" content=\"Mapa de Sitio Las Brisas Ixtapa. Contenido desglosado de toda la informaci\u00f3n relevante de forma pr\u00e1ctica para su b\u00fasqueda.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel Las Brisas Ixtapa - Mapa De Sitio | Contenido\" \/>\n<meta property=\"og:description\" content=\"Mapa de Sitio Las Brisas Ixtapa. Contenido desglosado de toda la informaci\u00f3n relevante de forma pr\u00e1ctica para su b\u00fasqueda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Brisas\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-22T19:58:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/\",\"url\":\"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/\",\"name\":\"Hotel Las Brisas Ixtapa - Mapa De Sitio | Contenido\",\"isPartOf\":{\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#website\"},\"datePublished\":\"2016-09-06T15:14:33+00:00\",\"dateModified\":\"2017-09-22T19:58:45+00:00\",\"description\":\"Mapa de Sitio Las Brisas Ixtapa. Contenido desglosado de toda la informaci\u00f3n relevante de forma pr\u00e1ctica para su b\u00fasqueda.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intlasbrisashotels.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ixtapa\",\"item\":\"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mapa de sitio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#website\",\"url\":\"https:\/\/www.intlasbrisashotels.com\/es\/\",\"name\":\"Las Brisas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intlasbrisashotels.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#organization\",\"name\":\"Grupo Brisas\",\"url\":\"https:\/\/www.intlasbrisashotels.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.intlasbrisashotels.com\/wp-content\/uploads\/2017\/06\/Grupo-Brisas-Logo.png\",\"contentUrl\":\"https:\/\/www.intlasbrisashotels.com\/wp-content\/uploads\/2017\/06\/Grupo-Brisas-Logo.png\",\"width\":201,\"height\":114,\"caption\":\"Grupo Brisas\"},\"image\":{\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel Las Brisas Ixtapa - Mapa De Sitio | Contenido","description":"Mapa de Sitio Las Brisas Ixtapa. Contenido desglosado de toda la informaci\u00f3n relevante de forma pr\u00e1ctica para su b\u00fasqueda.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Hotel Las Brisas Ixtapa - Mapa De Sitio | Contenido","og_description":"Mapa de Sitio Las Brisas Ixtapa. Contenido desglosado de toda la informaci\u00f3n relevante de forma pr\u00e1ctica para su b\u00fasqueda.","og_url":"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/","og_site_name":"Las Brisas","article_modified_time":"2017-09-22T19:58:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/","url":"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/","name":"Hotel Las Brisas Ixtapa - Mapa De Sitio | Contenido","isPartOf":{"@id":"https:\/\/www.intlasbrisashotels.com\/es\/#website"},"datePublished":"2016-09-06T15:14:33+00:00","dateModified":"2017-09-22T19:58:45+00:00","description":"Mapa de Sitio Las Brisas Ixtapa. Contenido desglosado de toda la informaci\u00f3n relevante de forma pr\u00e1ctica para su b\u00fasqueda.","breadcrumb":{"@id":"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/sitemap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intlasbrisashotels.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ixtapa","item":"https:\/\/www.intlasbrisashotels.com\/es\/ixtapa\/"},{"@type":"ListItem","position":3,"name":"Mapa de sitio"}]},{"@type":"WebSite","@id":"https:\/\/www.intlasbrisashotels.com\/es\/#website","url":"https:\/\/www.intlasbrisashotels.com\/es\/","name":"Las Brisas","description":"","publisher":{"@id":"https:\/\/www.intlasbrisashotels.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intlasbrisashotels.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.intlasbrisashotels.com\/es\/#organization","name":"Grupo Brisas","url":"https:\/\/www.intlasbrisashotels.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.intlasbrisashotels.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.intlasbrisashotels.com\/wp-content\/uploads\/2017\/06\/Grupo-Brisas-Logo.png","contentUrl":"https:\/\/www.intlasbrisashotels.com\/wp-content\/uploads\/2017\/06\/Grupo-Brisas-Logo.png","width":201,"height":114,"caption":"Grupo Brisas"},"image":{"@id":"https:\/\/www.intlasbrisashotels.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/pages\/4242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/comments?post=4242"}],"version-history":[{"count":0,"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/pages\/4242\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/pages\/1738"}],"wp:attachment":[{"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/media?parent=4242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}