{"id":15681,"date":"2023-10-20T13:04:26","date_gmt":"2023-10-20T13:04:26","guid":{"rendered":"https:\/\/www.intlasbrisashotels.com\/?page_id=15681"},"modified":"2023-10-20T13:04:26","modified_gmt":"2023-10-20T13:04:26","slug":"nuestras-suites","status":"publish","type":"page","link":"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/","title":{"rendered":"Nuestras Suites"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":1605,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"standard.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-15681","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nuestras Suites - Las Brisas<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestras Suites - Las Brisas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Brisas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/\",\"url\":\"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/\",\"name\":\"Nuestras Suites - Las Brisas\",\"isPartOf\":{\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#website\"},\"datePublished\":\"2023-10-20T13:04:26+00:00\",\"dateModified\":\"2023-10-20T13:04:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intlasbrisashotels.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acapulco\",\"item\":\"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuestras Suites\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#website\",\"url\":\"https:\/\/www.intlasbrisashotels.com\/es\/\",\"name\":\"Las Brisas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intlasbrisashotels.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#organization\",\"name\":\"Grupo Brisas\",\"url\":\"https:\/\/www.intlasbrisashotels.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.intlasbrisashotels.com\/wp-content\/uploads\/2017\/06\/Grupo-Brisas-Logo.png\",\"contentUrl\":\"https:\/\/www.intlasbrisashotels.com\/wp-content\/uploads\/2017\/06\/Grupo-Brisas-Logo.png\",\"width\":201,\"height\":114,\"caption\":\"Grupo Brisas\"},\"image\":{\"@id\":\"https:\/\/www.intlasbrisashotels.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuestras Suites - Las Brisas","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Nuestras Suites - Las Brisas","og_url":"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/","og_site_name":"Las Brisas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/","url":"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/","name":"Nuestras Suites - Las Brisas","isPartOf":{"@id":"https:\/\/www.intlasbrisashotels.com\/es\/#website"},"datePublished":"2023-10-20T13:04:26+00:00","dateModified":"2023-10-20T13:04:26+00:00","breadcrumb":{"@id":"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/nuestras-suites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intlasbrisashotels.com\/es\/"},{"@type":"ListItem","position":2,"name":"Acapulco","item":"https:\/\/www.intlasbrisashotels.com\/es\/acapulco\/"},{"@type":"ListItem","position":3,"name":"Nuestras Suites"}]},{"@type":"WebSite","@id":"https:\/\/www.intlasbrisashotels.com\/es\/#website","url":"https:\/\/www.intlasbrisashotels.com\/es\/","name":"Las Brisas","description":"","publisher":{"@id":"https:\/\/www.intlasbrisashotels.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intlasbrisashotels.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.intlasbrisashotels.com\/es\/#organization","name":"Grupo Brisas","url":"https:\/\/www.intlasbrisashotels.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.intlasbrisashotels.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.intlasbrisashotels.com\/wp-content\/uploads\/2017\/06\/Grupo-Brisas-Logo.png","contentUrl":"https:\/\/www.intlasbrisashotels.com\/wp-content\/uploads\/2017\/06\/Grupo-Brisas-Logo.png","width":201,"height":114,"caption":"Grupo Brisas"},"image":{"@id":"https:\/\/www.intlasbrisashotels.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/pages\/15681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/comments?post=15681"}],"version-history":[{"count":0,"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/pages\/15681\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/pages\/1605"}],"wp:attachment":[{"href":"https:\/\/www.intlasbrisashotels.com\/es\/wp-json\/wp\/v2\/media?parent=15681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}